{"id":315,"date":"2023-02-06T11:52:44","date_gmt":"2023-02-06T10:52:44","guid":{"rendered":"https:\/\/www.finanzen.net\/ratgeber\/ch\/2023\/02\/06\/swiss-dots-erfahrungen-der-otc-marktplatz-fuer-hebelprodukte-von-swissquote-im-test\/"},"modified":"2025-07-24T10:01:36","modified_gmt":"2025-07-24T08:01:36","slug":"swissdots-test-und-erfahrungen","status":"publish","type":"post","link":"https:\/\/www.finanzen.ch\/ratgeber\/swissdots-test-und-erfahrungen\/","title":{"rendered":"Swiss DOTS"},"content":{"rendered":"\n<div class=\"container container--narrow\">\n    <div class=\"header\">\n                    <div class=\"header__image\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"353\" src=\"https:\/\/www.finanzen.ch\/ratgeber\/wp-content\/uploads\/sites\/2\/2023\/02\/bitpanda.webp\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/www.finanzen.ch\/ratgeber\/wp-content\/uploads\/sites\/2\/2023\/02\/bitpanda.webp 768w, https:\/\/www.finanzen.ch\/ratgeber\/wp-content\/uploads\/sites\/2\/2023\/02\/bitpanda-300x138.webp 300w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>                            <\/div>\n                <div class=\"header__text\">\n                            <div class=\"headline headline--preline headline--h4 header__preline\">\n                    Angebot unter der Lupe                <\/div>\n                                        <h1 class=\"headline headline--h1 header__headline headline--has-preline\">\n                    Swiss DOTS Erfahrungen \u2013 der OTC-Marktplatz f\u00fcr Hebelprodukte von Swissquote im Test                <\/h1>\n                        <div class=\"header__excerpt flow-content\">\n                                    <p>SwissDots ist ein OTC-Handelsplatz (Over-the-Counter), der von Swissquote betrieben wird. Der Handelsplatz erm\u00f6glicht es Kunden, Hebelprodukte ausserhalb der regulierten B\u00f6rse zu handeln. Welche Auswahl an Finanzprodukten k\u00f6nnen Sie bei dem Anbieter erwarten? Wie benutzerfreundliche und sicher ist das Webangebot? Antworten auf diese und viele weitere Fragen finden Sie im Folgenden. Unsere wichtigsten Erkenntnisse und Tipps haben wir gleich zu Beginn f\u00fcr Sie zusammengefasst.<\/p>\n                            <\/div>\n            <div class=\"header__footer\">\n                <span class=\"header__meta\">\n                    <img loading=\"lazy\" decoding=\"async\" class=\"header__author-image\"\n                         src=\"https:\/\/secure.gravatar.com\/avatar\/04d3dcb21e2dac3164a2ba0d6d0b6e5e648b3bc6126615f5c387a1ba33db0d2d?s=116&#038;d=mm&#038;r=g\"\n                         width=\"58\"\n                         height=\"58\"\n                         alt=\"\">\n                    <span class=\"header__meta-info\">\n                        <span class=\"header__author-name\">\n                            von <a href=\"https:\/\/www.finanzen.ch\/ratgeber\/author\/benjamin-ressel\/\" title=\"Beitr\u00e4ge von Benjamin Ressel\" rel=\"author\" class=\"link link--no-underline\">Benjamin Ressel<\/a>                        <\/span>\n                        <span class=\"header__date\">\n                            <span class=\"hide-on-smartphone\">Aktualisiert am<\/span>\n                            <time datetime=\"2025-07-24 10:01\"\n                                  title=\"Aktualisiert am 24.07.2025\">\n                                24.07.25                            <\/time>\n                        <\/span>\n                    <\/span>\n                <\/span>\n\n                            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow\">\n    <div class=\"box box--type2 box--contrast01 box--small-margin short-info\">\n        <h3 class=\"headline headline--h3 headline--has-icon short-info__headline\" style=\"--headline-icon: url('https:\/\/www.finanzen.ch\/ratgeber\/wp-content\/themes\/fnet-ratgeber\/images\/icon-lightbulb-white.svg');\">\n                            Swiss DOTS Erfahrungen &#8211; Das Wichtigste in K\u00fcrze                    <\/h3>\n        <div class=\"box__content\">\n                            <div class=\"flow-content\">\n                    <ul>\n<li>Als OTC-Handelsplatz von Swissquote bietet Swiss DOTS* zehntausende von Hebelprodukten wie zum Beispiel <a href=\"#swissdots\">Warrants und andere Derivate an.<\/a><\/li>\n<li><strong>Produkt\u00adempfehlung<\/strong>: Trades \u00fcber den OTC-Handelsplatz Swiss DOTS von <a href=\"http:\/\/ratgeberlink.finanzen.net\/swissquote-ch-d-struki-swiss-dots\" target=\"_blank\" rel=\"noopener\"><strong>Swissquote*<\/strong><\/a>\u00a0kosten flat CHF 9. Damit ist das Geb\u00fchrenmodell sehr einfach gestaltet und die Kosten sind \u00fcbersichtlich kalkulierbar.<\/li>\n<li><strong>Tipp<\/strong>: <strong><a href=\"http:\/\/ratgeberlink.finanzen.net\/swissquote-ch-d-struki-swiss-dots\" target=\"_blank\" rel=\"noopener\">Swissquote*<\/a> <\/strong>bietet die M\u00f6glichkeit einer kostenfreien<a href=\"#Demo\"> Demo-Version<\/a> zum Testen der Oberfl\u00e4che und Tradingstrategien.<\/li>\n<li>Swiss DOTS geh\u00f6rt zur grossen Schweizer Bankengruppe Swissquote, die im Bereich Online-Trading Marktf\u00fchrer in allen Kantonen ist.<\/li>\n<li>OTC (Over-the-Counter)-Handel findet au\u00dferhalb von regulierten B\u00f6rsen statt, bei dem die Handelspartner direkt miteinander verhandeln. Sie kaufen die Hebelprodukte also direkt bei Swiss DOTS ohne weitere Zwischenh\u00e4ndler oder Geb\u00fchren an Dritte.<\/li>\n<li><strong>Hinweis<\/strong>: Der Over-the-Counter-Handel ist bei Swiss DOTS von 8 bis 22 Uhr m\u00f6glich. Sie profitieren also von verl\u00e4ngerten Handelszeiten, die im Vergleich zu den regul\u00e4ren B\u00f6rsenzeiten deutlich l\u00e4nger sind.<\/li>\n<\/ul>\n                <\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow\">\n    <div class=\"box toc\">\n        <h3 class=\"headline headline--h3 headline--has-icon\" style=\"--headline-icon: url('https:\/\/www.finanzen.ch\/ratgeber\/wp-content\/themes\/fnet-ratgeber\/images\/icon-list-blue.svg');\">\n                            Inhaltsverzeichnis                    <\/h3>\n        <div class=\"box__content\">\n            <ol class=\"toc__list js-toc-list\">\n                <!-- content generated by toc.js -->\n                            <\/ol>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow js-is-toc\" id=\"Swiss-DOTS-Test-im-berblick\" >\n                <h2            class=\"headline headline--h2\"\n                    >\n            Swiss DOTS: Test im \u00dcberblick        <\/h2>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Sie als Anleger und Kunde k\u00f6nnen bei <a title=\"Swissquote Swiss Dots Erfahrungen\" href=\"http:\/\/ratgeberlink.finanzen.net\/swissquote-ch-d-struki-swiss-dots\" target=\"_blank\" rel=\"sponsored nofollow noopener\"><b>Swissquote*<\/b><\/a> ein Trading-Konto er\u00f6ffnen, \u00fcber das Sie die Produkte von Swiss DOTS handeln k\u00f6nnen. Vorher ist es auch m\u00f6glich, die Funktionen mithilfe eines <a href=\"#Demo\">Demo-Kontos<\/a> zu testen. Der Broker bietet zudem eine <b>mobile App<\/b> an, mit der Sie auch unterwegs Ihre Trades immer im Blick behalten k\u00f6nnen.<\/p>\n<p>Die <b>Kosten<\/b> f\u00fcr das Depot und die <b>Ordergeb\u00fchren<\/b> werden von Swissquote transparent kommuniziert. Es gibt f\u00fcr Daytrader auch Flatoptionen bei den Ordergeb\u00fchren, um die Kosten zu deckeln.<\/p>\n<p>Wenn Sie Geld zum Traden bei Swissquote einzahlen wollen, k\u00f6nnen Sie das per Bank\u00fcberweisung, Kreditkarte oder Skrill. Bei den <b>Einzahlungen<\/b> gibt es keinen Mindestbetrag.<\/p>\n<p>Ein <b>Konto er\u00f6ffnen<\/b> Sie schnell und unkompliziert, indem Sie online ein Antragsformular ausf\u00fcllen. Die ersten drei Seiten m\u00fcssen Sie dann ausdrucken, unterschreiben und mit der Kopie eines Ausweisdokumentes bei Swissquote einschicken.<\/p>\n<p>Bei den <b>Auszahlungen<\/b> setzt das Unternehmen auf Sicherheit. Daher muss daf\u00fcr ein Antragsformular ausgef\u00fcllt werden und die \u00dcberpr\u00fcfung kann einige Tage in Anspruch nehmen \u2013 allerdings sind Sie so auf der sichereren Seite. Die Auszahlung auf eine Kreditkarte ist nicht m\u00f6glich.<\/p>\n<p><b>Kontakt<\/b> mit Swissquote nehmen sie am besten \u00fcber den Livechat, das E-Mail-Kontaktformular, telefonisch oder per Fax auf.<\/p>\n<p>Die Swissquote-Bank stellt alle n\u00f6tigen <b>Steuerdokumente<\/b> kostenfrei zur Verf\u00fcgung im Rahmen der Corporate Actions, dazu geh\u00f6ren zum Beispiel K\u00e4ufe, Verk\u00e4ufe und Dividendeneing\u00e4nge. F\u00fcr CHF 100 k\u00f6nnen Sie auch ein konsolidiertes Steuerdokument anfordern.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow js-is-toc\" id=\"Swissquote--Der-Anbieter-von-Swiss-DOTS-im-berblick\" >\n                <h2            class=\"headline headline--h2\"\n                    >\n            Swissquote \u2013 Der Anbieter von Swiss DOTS im \u00dcberblick        <\/h2>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p><a title=\"Swissquote Swiss Dots Erfahrungen\" href=\"http:\/\/ratgeberlink.finanzen.net\/swissquote-ch-d-struki-swiss-dots\" target=\"_blank\" rel=\"sponsored nofollow noopener\"><b>Swissquote*<\/b><\/a> ist eine Schweizer Bankengruppe mit Hauptsitz in Gland. Als Finanzplattform wurde das Unternehmen bereits 1996 gegr\u00fcndet, 2001 folgte der Gang an die B\u00f6rse sowie die Banklizenz. Damit war Swissquote <b>die erste reine Online-Bank der Schweiz<\/b>.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow js-is-toc\" id=\"swissdots\" >\n                <h2            class=\"headline headline--h2\"\n                    >\n            Mit Swiss DOTS Warrants und andere Derivate handeln        <\/h2>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Der OTC-Marktplatz <b>Swiss DOTS*<\/b> bietet Ihnen eine Auswahl aus Zehntausenden Hebelprodukten. Darunter befinden sich Warrants, Knock-out Warrants, Mini-Futures und Faktor-Zertifikate, die f\u00fcr verschiedene Risiko-Profile geeignet sind. Die Emittenten, mit denen Swiss DOTS zusammenarbeiten, sind: <a title=\"Vontobel\" href=\"https:\/\/www.vontobel.com\/de-ch\/\" target=\"_blank\" rel=\"noopener\">Vontobel<\/a>, <a title=\"Goldman Sachs\" href=\"https:\/\/www.goldmansachs.com\/worldwide\/switzerland\/de\/\" target=\"_blank\" rel=\"noopener\">Goldman Sachs<\/a>, <a title=\"BNP Paribas\" href=\"https:\/\/www.bnpparibasmarkets.ch\/\" target=\"_blank\" rel=\"noopener\">BNP Paribas<\/a>, <a title=\"Soci\u00e9t\u00e9 G\u00e9n\u00e9rale\" href=\"https:\/\/www.societegenerale.ch\/\" target=\"_blank\" rel=\"noopener\">Soci\u00e9t\u00e9 G\u00e9n\u00e9rale<\/a> und <a title=\"UBS\" href=\"https:\/\/www.ubs.com\/ch\/de.html\" target=\"_blank\" rel=\"noopener\">UBS<\/a>. Der Anbieter stellt Einsteigern kostenlose E-Books sowie mehrere Erkl\u00e4rvideos zur Verf\u00fcgung, in denen Swiss DOTS und der Handel mit Warrants einfach erkl\u00e4rt werden. Sie haben als Kunde die Wahl zwischen Limit-, Market-, Stop-Loss und Stop-Limit-Orders. Der Handel auf Swiss DOTS ist von 8 bis 22 Uhr m\u00f6glich.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow\" >\n                <h3            class=\"headline headline--h3\"\n                    >\n            Swiss DOTS-Produkte im \u00dcberblick        <\/h3>\n        <\/div>\n\n\n<div class=\"container container--narrow\" >\n                            <div class=\"table-container\">\n        \n                <table class=\"table\">\n                                                                <thead>\n                            <tr>\n                                                                    <th>\n                                                                            <\/th>\n                                                                    <th>\n                                        Warrants\t                                    <\/th>\n                                                                    <th>\n                                        Knock-out Warrants                                    <\/th>\n                                                                    <th>\n                                        Mini-Futures\t                                    <\/th>\n                                                                    <th>\n                                        Faktor-Zertifikate                                    <\/th>\n                                                            <\/tr>\n                        <\/thead>\n                                                                <tbody>\n                                                            <tr>\n                                                                            <td>\n                                            Hebel\t                                        <\/td>\n                                                                            <td>\n                                            Variabel\t                                        <\/td>\n                                                                            <td>\n                                            Variabel\t                                        <\/td>\n                                                                            <td>\n                                            Variabel\t                                        <\/td>\n                                                                            <td>\n                                            Konstant                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            Volatilit\u00e4tseffekt\t                                        <\/td>\n                                                                            <td>\n                                            Ja, erheblich\t                                        <\/td>\n                                                                            <td>\n                                            Nein\t                                        <\/td>\n                                                                            <td>\n                                            Nein\t                                        <\/td>\n                                                                            <td>\n                                            Nein\t                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            F\u00e4lligkeit\t                                        <\/td>\n                                                                            <td>\n                                            Begrenzt\t                                        <\/td>\n                                                                            <td>\n                                            Offen\t                                        <\/td>\n                                                                            <td>\n                                            Offen\t                                        <\/td>\n                                                                            <td>\n                                            Offen\t                                        <\/td>\n                                                                    <\/tr>\n                                                            <tr>\n                                                                            <td>\n                                            Knock-out-\/vorzeitiger Totalverlust                                        <\/td>\n                                                                            <td>\n                                            Nein\t                                        <\/td>\n                                                                            <td>\n                                            Ja\t                                        <\/td>\n                                                                            <td>\n                                            Ja\t                                        <\/td>\n                                                                            <td>\n                                            Nein                                        <\/td>\n                                                                    <\/tr>\n                                                    <\/tbody>\n                                    <\/table>\n                    <\/div>\n            <\/div>\n\n\n\n<div class=\"container container--narrow js-is-toc\" id=\"Swiss-DOTS-Kosten-fr-Anleger\" >\n                <h2            class=\"headline headline--h2\"\n                    >\n            Swiss DOTS: Kosten f\u00fcr Anleger        <\/h2>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Die Depotf\u00fchrungsgeb\u00fchren f\u00fcr Wertschriften betragen bei <a title=\"Swissquote Swiss Dots Erfahrungen\" href=\"http:\/\/ratgeberlink.finanzen.net\/swissquote-ch-d-struki-swiss-dots\" target=\"_blank\" rel=\"sponsored nofollow noopener\"><b>Swissquote*<\/b><\/a> 0,025 Prozent Ihrer Einlage pro Quartal, mindestens CHF 15 und maximal CHF 50. Das Trading auf Swiss DOTS gibt es f\u00fcr flat CHF 9.-, ausgenommen Fremdgeb\u00fchren, allf\u00e4llige Stempelsteuer und Echtzeitgeb\u00fchren. Das lohnt sich vor allem f\u00fcr Anleger, die gro\u00dfe Volumen traden und ihre Handelsgeb\u00fchren langfristig kalkulieren wollen.<\/p>\n<p>Bei Abbuchungen auf andere Konten verlangt Swissquote eine Geb\u00fchr, die innerhalb der Schweiz CHF 2 betr\u00e4gt. Die Kosten f\u00fcr \u00dcberweisungen ins Ausland und in fremden W\u00e4hrungen sind in einer <a title=\"Swissquote Zahlungsgeb\u00fchren\" href=\"https:\/\/de.swissquote.com\/forex\/resources\/account-management\/payment-fees\" target=\"_blank\" rel=\"noopener\">ausf\u00fchrlichen Tabelle<\/a> aufgeschl\u00fcsselt.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow \" >\n    <div class=\"highlightbox-container\">\n                    <div class=\"highlightbox box\">\n                                    <h2                        class=\"headline headline--h3\"\n                                            >\n                        Von erfahrenen Investment-Profis lernen!                    <\/h2>\n                                <div class=\"box__content\">\n                                            <div class=\"flow-content\">\n                            <p>Noch mehr Expertenwissen zu Aktien, ETFs &amp; Co. gibt es in unseren kostenfreien Online-Seminaren. Fondsmanager, Analysten, Profi-Trader und andere Experten stehen Ihnen Rede und Antwort:<\/p>\n<p><em>Welche Anlagestrategien sind erfolgversprechend?<\/em><br \/>\n<em>Welche Aktien, Fonds und Derivate empfehlen die B\u00f6rsenprofis?<\/em><br \/>\n<em>Jetzt einsteigen oder eher abwarten?<\/em><\/p>\n<p><em><strong>Informieren Sie sich jetzt \u00fcber unsere aktuellen Webinare:<\/strong><\/em><br \/>\n<a href=\"https:\/\/www.finanzen.net\/webinare\">Hier finden Sie alle anstehenden Veranstaltungen sowie Live-Mitschnitte vergangener Webinare.<\/a><\/p>\n                        <\/div>\n                                                        <\/div>\n            <\/div>\n            <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow js-is-toc\" id=\"Kontoerffnung-bei-Swissquote-um-ber-Swiss-DOTS-zu-handeln\" >\n                <h2            class=\"headline headline--h2\"\n                    >\n            Kontoer\u00f6ffnung bei Swissquote, um \u00fcber Swiss DOTS zu handeln        <\/h2>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Wenn Sie ein vollwertiges Konto einrichten wollen, werden Sie zu einem vierschrittigen Anmeldungsprozess geleitet. Dort m\u00fcssen Sie dann nacheinander Ihre Kontaktdaten und Finanzinformationen angeben und ein Kunden- sowie Anlageprofil erstellen. Jedes Konto besitzt eine in der Schweiz eingetragene IBAN und durch das eBanking-Portal k\u00f6nnen Sie Geld zwischen den Konten transferieren. Das Antragsformular schicken Sie dann mit der Kopie eines Ausweisdokumentes ein.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow\" id=\"Demo\" >\n                <h3            class=\"headline headline--h3\"\n                    >\n            Was bietet die Demoversion des Swissquote-Brokers?        <\/h3>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Das Einrichten eines Demo-Kontos ist kostenfrei und einfach, hier verlangt der Broker lediglich ein paar Grunddaten. Nach der Freischaltung des Kontos bekommen Sie 10&#8217;000 US-Dollar &#171;Spielgeld&#187; und k\u00f6nnen damit risikofrei Trades simulieren, um die Funktionen des Brokers zu testen oder Investmentstrategien zu erproben. Das Demo-Konto kann nach der Aktivierung 30 Tage lang genutzt werden und pro E-Mail-Adresse kann man nur einmal eine Demo-Version registrieren.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow js-is-toc\" id=\"Swissquote-Tests-und-Erfahrungen-mit-dem-Anbieter-von-Swiss-DOTS\" >\n                <h2            class=\"headline headline--h2\"\n                    >\n            Swissquote: Tests und Erfahrungen mit dem Anbieter von Swiss DOTS        <\/h2>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Im Schnitt wird <a title=\"Swissquote Swiss Dots Erfahrungen\" href=\"http:\/\/ratgeberlink.finanzen.net\/swissquote-ch-d-struki-swiss-dots\" target=\"_blank\" rel=\"sponsored nofollow noopener\"><b>Swissquote*<\/b><\/a> auf den meisten Testseiten positiv bewertet. Besonders die Seriosit\u00e4t, Sicherheit und gute Kosten\u00fcbersicht werden bei der Bank gelobt. Teilweise sind die Bewertungen aber auch widerspr\u00fcchlich: Einige Seiten heben den guten Kundenservice hervor, andere bem\u00e4ngeln diesen wiederum. Einige Anleger monieren relativ hohe Geb\u00fchren, andere loben wiederum die Kostendeckelung. Machen Sie sich am besten selbst einen Eindruck! Verbesserungspotenzial sehen wir bei unserer Swissquote-Erfahrung in der Hinsicht, dass man nicht f\u00fcr jede Asset-Klasse ein neues Depot er\u00f6ffnen sollte.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow js-is-toc\" id=\"Sicherheit-bei-Swiss-DOTS\" >\n                <h2            class=\"headline headline--h2\"\n                    >\n            Sicherheit bei Swiss DOTS        <\/h2>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Das Unternehmen Swissquote, welches Swiss DOTS auflegt, besitzt eine Banklizenz, die im Jahr 2000 von der Eidgen\u00f6ssischen Bankenkommission erteilt wurde. Ausserdem wird die Bank von der Eidgen\u00f6ssischen Finanzaufsicht (FINMA) kontrolliert. Ihre Einlagen sind nach Schweizer Recht mit bis zu CHF 100&#8217;000 pro Kunde abgesichert.<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow js-is-toc\" id=\"Swissquote-Service-und-Kontakt\" >\n                <h2            class=\"headline headline--h2\"\n                    >\n            Swissquote: Service und Kontakt        <\/h2>\n        <\/div>\n\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"text\">\n        <div class=\"text__inner flow-content\">\n                            <p>Swissquote Bank<br \/>\nCh. de la Cr\u00e9taux 33<br \/>\nCase Postale 319<br \/>\nCH-1196 Gland.<br \/>\nTelefon: +41 22 999 94 11 (8 bis 22 Uhr)<br \/>\nFax: +41 22 999 94 12<br \/>\nHomepage: https:\/\/www.swissquote.com (hier finden Sie auch den Live-Chat und das E-Mail-Kontaktformular)<\/p>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container container--narrow js-is-toc\" id=\"Swiss-DOTS--das-sollten-Sie-tun\" >\n                <h2            class=\"headline headline--h2\"\n                    >\n            Swiss DOTS &#8211; das sollten Sie tun        <\/h2>\n        <\/div>\n\n\n\n<div class=\"container container--narrow \" >\n            <ol class=\"ordered-list ordered-list--type1\">\n                           <li class=\"ordered-list__item\">\n                    <div class=\"ordered-list__content\">\n                                                                            <div class=\"ordered-list__text\">\n                                <p>\u00dcberlegen Sie sich, mit welchen Anlageklassen Sie handeln wollen und er\u00f6ffnen Sie dementsprechend eines oder mehrere Depots bei <a href=\"http:\/\/ratgeberlink.finanzen.net\/swissquote-ch-d-struki-swiss-dots\" target=\"_blank\" rel=\"noopener\"><strong>Swissquote*<\/strong><\/a>.<\/p>\n                            <\/div>\n                                            <\/div>\n                <\/li>\n                            <li class=\"ordered-list__item\">\n                    <div class=\"ordered-list__content\">\n                                                                            <div class=\"ordered-list__text\">\n                                <p>Nutzen Sie die M\u00f6glichkeit des Demokontos, wenn Sie sich bei der Wahl Ihrer Investments noch unsicher sind \u2013 oder einfach um die Funktionen des Online-Brokers kennenzulernen.<\/p>\n                            <\/div>\n                                            <\/div>\n                <\/li>\n                            <li class=\"ordered-list__item\">\n                    <div class=\"ordered-list__content\">\n                                                                            <div class=\"ordered-list__text\">\n                                <p>Wenn Sie einsch\u00e4tzen k\u00f6nnen, wie viele Trades Sie in einem bestimmten Zeitraum machen m\u00f6chten, k\u00f6nnen Sie durch das Flatsystem Ordergeb\u00fchren sparen.<\/p>\n                            <\/div>\n                                            <\/div>\n                <\/li>\n                            <li class=\"ordered-list__item\">\n                    <div class=\"ordered-list__content\">\n                                                                            <div class=\"ordered-list__text\">\n                                <p>Laden Sie sich die Swissquote-App auf Ihr Handy und behalten Sie jederzeit Ihre Konten im Blick.<\/p>\n                            <\/div>\n                                            <\/div>\n                <\/li>\n                    <\/ol>\n    <\/div>\n\n\n<div class=\"container container--narrow\" >\n    <div class=\"disclaimer flow-content\">\n                    <small>\n                <p>*Das bedeutet das Sternchen: Unsere Ratgeber-Artikel sind objektiv recherchiert und unabh\u00e4ngig erstellt. Wir wollen so m\u00f6glichst vielen Menschen helfen, eigenst\u00e4ndig Verm\u00f6gen aufzubauen und in Finanzfragen die richtigen Entscheidungen zu treffen. Damit unsere Informationen kostenlos abrufbar sind, werden manchmal Klicks auf Verlinkungen verg\u00fctet. Diese sogenannten Affiliate Links kennzeichnen wir mit einem Sternchen. Geld bekommt die finanzen.net GmbH, aber nie der Autor individuell, wenn Leser auf einen solchen Link klicken oder beim Anbieter einen Vertrag abschliessen. Ob die finanzen.net GmbH eine Verg\u00fctung erh\u00e4lt und in welcher H\u00f6he, hat keinerlei Einfluss auf die Produktempfehlungen. F\u00fcr die Ratgeber-Redaktion ist ausschliesslich wichtig, ob ein Angebot gut f\u00fcr Anleger und Sparer ist.<\/p>\n            <\/small>\n                    <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>SwissDots ist ein OTC-Handelsplatz (Over-the-Counter), der von Swissquote betrieben wird. Der Handelsplatz erm\u00f6glicht es Kunden, Hebelprodukte ausserhalb der regulierten B\u00f6rse zu handeln. Welche Auswahl an Finanzprodukten k\u00f6nnen Sie bei dem Anbieter erwarten? Wie benutzerfreundliche und sicher ist das Webangebot? Antworten auf diese und viele weitere Fragen finden Sie im Folgenden. Unsere wichtigsten Erkenntnisse und Tipps haben wir gleich zu Beginn f\u00fcr Sie zusammengefasst.<\/p>\n","protected":false},"author":9,"featured_media":1186,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[31],"tags":[41,42,43,44],"class_list":["post-315","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-anbieter","tag-online-broker","tag-swissquote","tag-swissquote-bank","tag-swissquote-trader"],"acf":[],"yoast_head":"<title>Swiss DOTS Erfahrungen \u2013 der OTC-Marktplatz f\u00fcr Hebelprodukte von Swissquote im Test | finanzen.ch<\/title>\n<meta name=\"description\" content=\"Swiss DOTS haben wir genau gepr\u00fcft. Lesen Sie in diesem Ratgeber unsere Erfahrungen mit dem OTC-Marktplatz von Swissquote.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.finanzen.ch\/ratgeber\/swissdots-test-und-erfahrungen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Swiss DOTS Erfahrungen \u2013 der OTC-Marktplatz f\u00fcr Hebelprodukte von Swissquote im Test | finanzen.ch\" \/>\n<meta property=\"og:description\" content=\"Swiss DOTS haben wir genau gepr\u00fcft. Lesen Sie in diesem Ratgeber unsere Erfahrungen mit dem OTC-Marktplatz von Swissquote.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.finanzen.ch\/ratgeber\/swissdots-test-und-erfahrungen\/\" \/>\n<meta property=\"og:site_name\" content=\"Ratgeber: Wissenswertes rund um die Geldanlage | finanzen.ch\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-06T10:52:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-24T08:01:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.finanzen.ch\/ratgeber\/wp-content\/uploads\/sites\/2\/2023\/02\/bitpanda.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"353\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Benjamin Ressel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Benjamin Ressel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>","yoast_head_json":{"title":"Swiss DOTS Erfahrungen \u2013 der OTC-Marktplatz f\u00fcr Hebelprodukte von Swissquote im Test | finanzen.ch","description":"Swiss DOTS haben wir genau gepr\u00fcft. Lesen Sie in diesem Ratgeber unsere Erfahrungen mit dem OTC-Marktplatz von Swissquote.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.finanzen.ch\/ratgeber\/swissdots-test-und-erfahrungen\/","og_locale":"de_DE","og_type":"article","og_title":"Swiss DOTS Erfahrungen \u2013 der OTC-Marktplatz f\u00fcr Hebelprodukte von Swissquote im Test | finanzen.ch","og_description":"Swiss DOTS haben wir genau gepr\u00fcft. Lesen Sie in diesem Ratgeber unsere Erfahrungen mit dem OTC-Marktplatz von Swissquote.","og_url":"https:\/\/www.finanzen.ch\/ratgeber\/swissdots-test-und-erfahrungen\/","og_site_name":"Ratgeber: Wissenswertes rund um die Geldanlage | finanzen.ch","article_published_time":"2023-02-06T10:52:44+00:00","article_modified_time":"2025-07-24T08:01:36+00:00","og_image":[{"width":768,"height":353,"url":"https:\/\/www.finanzen.ch\/ratgeber\/wp-content\/uploads\/sites\/2\/2023\/02\/bitpanda.webp","type":"image\/webp"}],"author":"Benjamin Ressel","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Benjamin Ressel","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.finanzen.ch\/ratgeber\/swissdots-test-und-erfahrungen\/#article","isPartOf":{"@id":"https:\/\/www.finanzen.ch\/ratgeber\/swissdots-test-und-erfahrungen\/"},"author":{"name":"Benjamin Ressel","@id":"https:\/\/www.finanzen.ch\/ratgeber\/#\/schema\/person\/1fbfaf322c57d019ea8974ee85eb041d"},"headline":"Swiss DOTS","datePublished":"2023-02-06T10:52:44+00:00","dateModified":"2025-07-24T08:01:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.finanzen.ch\/ratgeber\/swissdots-test-und-erfahrungen\/"},"wordCount":1385,"image":{"@id":"https:\/\/www.finanzen.ch\/ratgeber\/swissdots-test-und-erfahrungen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.finanzen.ch\/ratgeber\/wp-content\/uploads\/sites\/2\/2023\/02\/bitpanda.webp","keywords":["online broker","swissquote","swissquote bank","swissquote trader"],"articleSection":["Anbieter"],"inLanguage":"de-CH"},{"@type":"WebPage","@id":"https:\/\/www.finanzen.ch\/ratgeber\/swissdots-test-und-erfahrungen\/","url":"https:\/\/www.finanzen.ch\/ratgeber\/swissdots-test-und-erfahrungen\/","name":"Swiss DOTS Erfahrungen \u2013 der OTC-Marktplatz f\u00fcr Hebelprodukte von Swissquote im Test | finanzen.ch","isPartOf":{"@id":"https:\/\/www.finanzen.ch\/ratgeber\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.finanzen.ch\/ratgeber\/swissdots-test-und-erfahrungen\/#primaryimage"},"image":{"@id":"https:\/\/www.finanzen.ch\/ratgeber\/swissdots-test-und-erfahrungen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.finanzen.ch\/ratgeber\/wp-content\/uploads\/sites\/2\/2023\/02\/bitpanda.webp","datePublished":"2023-02-06T10:52:44+00:00","dateModified":"2025-07-24T08:01:36+00:00","author":{"@id":"https:\/\/www.finanzen.ch\/ratgeber\/#\/schema\/person\/1fbfaf322c57d019ea8974ee85eb041d"},"description":"Swiss DOTS haben wir genau gepr\u00fcft. Lesen Sie in diesem Ratgeber unsere Erfahrungen mit dem OTC-Marktplatz von Swissquote.","breadcrumb":{"@id":"https:\/\/www.finanzen.ch\/ratgeber\/swissdots-test-und-erfahrungen\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.finanzen.ch\/ratgeber\/swissdots-test-und-erfahrungen\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/www.finanzen.ch\/ratgeber\/swissdots-test-und-erfahrungen\/#primaryimage","url":"https:\/\/www.finanzen.ch\/ratgeber\/wp-content\/uploads\/sites\/2\/2023\/02\/bitpanda.webp","contentUrl":"https:\/\/www.finanzen.ch\/ratgeber\/wp-content\/uploads\/sites\/2\/2023\/02\/bitpanda.webp","width":768,"height":353},{"@type":"BreadcrumbList","@id":"https:\/\/www.finanzen.ch\/ratgeber\/swissdots-test-und-erfahrungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.finanzen.ch\/ratgeber\/"},{"@type":"ListItem","position":2,"name":"Anbieter","item":"https:\/\/www.finanzen.ch\/ratgeber\/category\/anbieter\/"},{"@type":"ListItem","position":3,"name":"Swiss DOTS"}]},{"@type":"WebSite","@id":"https:\/\/www.finanzen.ch\/ratgeber\/#website","url":"https:\/\/www.finanzen.ch\/ratgeber\/","name":"Ratgeber: Wissenswertes rund um die Geldanlage | finanzen.ch","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.finanzen.ch\/ratgeber\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Person","@id":"https:\/\/www.finanzen.ch\/ratgeber\/#\/schema\/person\/1fbfaf322c57d019ea8974ee85eb041d","name":"Benjamin Ressel","image":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/secure.gravatar.com\/avatar\/04d3dcb21e2dac3164a2ba0d6d0b6e5e648b3bc6126615f5c387a1ba33db0d2d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04d3dcb21e2dac3164a2ba0d6d0b6e5e648b3bc6126615f5c387a1ba33db0d2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04d3dcb21e2dac3164a2ba0d6d0b6e5e648b3bc6126615f5c387a1ba33db0d2d?s=96&d=mm&r=g","caption":"Benjamin Ressel"},"description":"Redakteur","url":"https:\/\/www.finanzen.ch\/ratgeber\/author\/benjamin-ressel\/"}]}},"_links":{"self":[{"href":"https:\/\/www.finanzen.ch\/ratgeber\/wp-json\/wp\/v2\/posts\/315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.finanzen.ch\/ratgeber\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.finanzen.ch\/ratgeber\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.finanzen.ch\/ratgeber\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.finanzen.ch\/ratgeber\/wp-json\/wp\/v2\/comments?post=315"}],"version-history":[{"count":4,"href":"https:\/\/www.finanzen.ch\/ratgeber\/wp-json\/wp\/v2\/posts\/315\/revisions"}],"predecessor-version":[{"id":22125,"href":"https:\/\/www.finanzen.ch\/ratgeber\/wp-json\/wp\/v2\/posts\/315\/revisions\/22125"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.finanzen.ch\/ratgeber\/wp-json\/wp\/v2\/media\/1186"}],"wp:attachment":[{"href":"https:\/\/www.finanzen.ch\/ratgeber\/wp-json\/wp\/v2\/media?parent=315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.finanzen.ch\/ratgeber\/wp-json\/wp\/v2\/categories?post=315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.finanzen.ch\/ratgeber\/wp-json\/wp\/v2\/tags?post=315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}